{"id":24,"count":141,"description":"","link":"https:\/\/stebby.eu\/et\/kategooria\/liikumine\/","name":"Liikumine","slug":"liikumine","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liikumine - Stebby<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stebby.eu\/category\/activity\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liikumine - Stebby\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stebby.eu\/category\/activity\/\" \/>\n<meta property=\"og:site_name\" content=\"Stebby\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/stebby.eu\/wp-content\/uploads\/2020\/10\/stebby_fb_share.png?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/stebby.eu\/category\/activity\/\",\"url\":\"https:\/\/stebby.eu\/category\/activity\/\",\"name\":\"Liikumine - Stebby\",\"isPartOf\":{\"@id\":\"https:\/\/stebby.eu\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/stebby.eu\/category\/activity\/#breadcrumb\"},\"inLanguage\":\"et\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stebby.eu\/category\/activity\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/stebby.eu\/et\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activity\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stebby.eu\/#website\",\"url\":\"https:\/\/stebby.eu\/\",\"name\":\"Stebby\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/stebby.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stebby.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stebby.eu\/#organization\",\"name\":\"Stebby\",\"url\":\"https:\/\/stebby.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/stebby.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stebby.eu\/wp-content\/uploads\/2020\/10\/stebby3-1.png\",\"contentUrl\":\"https:\/\/stebby.eu\/wp-content\/uploads\/2020\/10\/stebby3-1.png\",\"width\":256,\"height\":256,\"caption\":\"Stebby\"},\"image\":{\"@id\":\"https:\/\/stebby.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/stebby\/\",\"https:\/\/instagram.com\/stebby.eesti\",\"https:\/\/www.linkedin.com\/company\/stebby\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liikumine - Stebby","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stebby.eu\/category\/activity\/","og_locale":"et_EE","og_type":"article","og_title":"Liikumine - Stebby","og_url":"https:\/\/stebby.eu\/category\/activity\/","og_site_name":"Stebby","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/stebby.eu\/wp-content\/uploads\/2020\/10\/stebby_fb_share.png?fit=1200%2C630&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/stebby.eu\/category\/activity\/","url":"https:\/\/stebby.eu\/category\/activity\/","name":"Liikumine - Stebby","isPartOf":{"@id":"https:\/\/stebby.eu\/#website"},"breadcrumb":{"@id":"https:\/\/stebby.eu\/category\/activity\/#breadcrumb"},"inLanguage":"et"},{"@type":"BreadcrumbList","@id":"https:\/\/stebby.eu\/category\/activity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stebby.eu\/et\/"},{"@type":"ListItem","position":2,"name":"Activity"}]},{"@type":"WebSite","@id":"https:\/\/stebby.eu\/#website","url":"https:\/\/stebby.eu\/","name":"Stebby","description":"","publisher":{"@id":"https:\/\/stebby.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stebby.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/stebby.eu\/#organization","name":"Stebby","url":"https:\/\/stebby.eu\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/stebby.eu\/#\/schema\/logo\/image\/","url":"https:\/\/stebby.eu\/wp-content\/uploads\/2020\/10\/stebby3-1.png","contentUrl":"https:\/\/stebby.eu\/wp-content\/uploads\/2020\/10\/stebby3-1.png","width":256,"height":256,"caption":"Stebby"},"image":{"@id":"https:\/\/stebby.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/stebby\/","https:\/\/instagram.com\/stebby.eesti","https:\/\/www.linkedin.com\/company\/stebby\/"]}]}},"_links":{"self":[{"href":"https:\/\/stebby.eu\/et\/wp-json\/wp\/v2\/categories\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stebby.eu\/et\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stebby.eu\/et\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/stebby.eu\/et\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}